{"id":12112,"date":"2025-03-27T16:33:14","date_gmt":"2025-03-27T20:33:14","guid":{"rendered":"https:\/\/icardio.ca\/el-sincope-cardiaco\/"},"modified":"2025-03-27T18:13:43","modified_gmt":"2025-03-27T22:13:43","slug":"el-sincope-cardiaco","status":"publish","type":"post","link":"https:\/\/icardio.ca\/es\/el-sincope-cardiaco\/","title":{"rendered":"El s\u00edncope card\u00edaco"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12112\" class=\"elementor elementor-12112 elementor-12095\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb9dedb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb9dedb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-088fd76\" data-id=\"088fd76\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26379fa elementor-widget elementor-widget-heading\" data-id=\"26379fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">El s\u00edncope card\u00edaco<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dd6986 elementor-align-center elementor-widget elementor-widget-post-info\" data-id=\"1dd6986\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-6610920 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/icardio.ca\/es\/author\/icardio\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">\u00c9crit par<\/span>\n\t\t\t\t\t\t\t\t\t\ticardio\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-a890a19 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/icardio.ca\/es\/2025\/03\/27\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Publi\u00e9 le <\/span>\n\t\t\t\t\t\t\t\t\t\t<time>27 marzo 2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cc21ce elementor-widget elementor-widget-elementskit-breadcrumb\" data-id=\"4cc21ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><ol class=\"ekit-breadcrumb\"><li class=\"ekit_breadcrumbs_start\"><a href=\"https:\/\/icardio.ca\/es\/\">Bienvenido<\/a><\/li><\/ol><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d446bdb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d446bdb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-54eda83\" data-id=\"54eda83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2caa6b47 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"2caa6b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1235\" height=\"995\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/coeur-noir.png\" class=\"attachment-full size-full wp-image-12113\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/coeur-noir.png 1235w, https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/coeur-noir-300x242.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/coeur-noir-1024x825.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/coeur-noir-768x619.png 768w\" sizes=\"(max-width: 1235px) 100vw, 1235px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86944b3 e-flex e-con-boxed e-con e-parent\" data-id=\"86944b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1bc77a4 e-flex e-con-boxed e-con e-child\" data-id=\"1bc77a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e712dd6 elementor-widget elementor-widget-text-editor\" data-id=\"e712dd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La s\u00edncope es un desmayo temporal provocado por una disminuci\u00f3n del flujo sangu\u00edneo al cerebro. Puede tener varias causas, que var\u00edan seg\u00fan los individuos y las circunstancias.<\/p><p><strong>Para leer: <\/strong><a href=\"https:\/\/icardio.ca\/es\/la-sincope-o-la-perdida-de-conocimiento\/\"><span style=\"text-decoration: underline;\"><em>La s\u00edncope o la p\u00e9rdida de conocimiento<\/em><\/span><\/a><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fdaf0dc e-flex e-con-boxed e-con e-parent\" data-id=\"fdaf0dc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f4b119 e-flex e-con-boxed e-con e-child\" data-id=\"3f4b119\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5a8326 elementor-widget elementor-widget-heading\" data-id=\"f5a8326\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El s\u00edncope card\u00edaco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31c7753 e-flex e-con-boxed e-con e-parent\" data-id=\"31c7753\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c9fbea e-con-full e-flex e-con e-child\" data-id=\"4c9fbea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77a6b17 elementor-widget elementor-widget-text-editor\" data-id=\"77a6b17\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como su nombre lo indica, el s\u00edncope card\u00edaco es <strong>causado por un problema en el coraz\u00f3n<\/strong>. Es una de las formas de s\u00edncope que requiere especial atenci\u00f3n, ya que puede ser se\u00f1al de un trastorno card\u00edaco m\u00e1s serio.<\/p><p>En la gran mayor\u00eda de los casos, est\u00e1 relacionado con un <strong>trastorno del ritmo<\/strong> card\u00edaco.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33a0b38 e-flex e-con-boxed e-con e-parent\" data-id=\"33a0b38\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1944850 e-con-full e-flex e-con e-child\" data-id=\"1944850\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-486954c elementor-widget elementor-widget-text-editor\" data-id=\"486954c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestro coraz\u00f3n posee un peque\u00f1o grupo de c\u00e9lulas llamado \u201cmarcapasos natural\u201d que act\u00faa como un <strong>director de orquesta<\/strong> para regular los latidos. Env\u00eda se\u00f1ales el\u00e9ctricas a trav\u00e9s de una red sofisticada que coordina cada contracci\u00f3n.<\/p><p><strong>Lectura sugerida:<\/strong> <a href=\"https:\/\/icardio.ca\/es\/el-sistema-electrico\/\"><span style=\"text-decoration: underline;\"><em>El sistema el\u00e9ctrico<\/em><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f748f7f e-con-full e-flex e-con e-child\" data-id=\"f748f7f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beb28ae elementor-widget elementor-widget-image\" data-id=\"beb28ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/Anatomie-chef-orches-sans-nom.png\" class=\"attachment-large size-large wp-image-3657\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/Anatomie-chef-orches-sans-nom.png 872w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/Anatomie-chef-orches-sans-nom-300x169.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/Anatomie-chef-orches-sans-nom-768x432.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3b646d e-flex e-con-boxed e-con e-parent\" data-id=\"c3b646d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-380f4d6 e-con-full e-flex e-con e-child\" data-id=\"380f4d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef7fd22 elementor-widget elementor-widget-text-editor\" data-id=\"ef7fd22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A veces, este sistema puede ralentizarse de forma anormal: el coraz\u00f3n late demasiado lento, lo que se denomina <strong>bradicardia<\/strong>.<\/p><p>Por el contrario, tambi\u00e9n puede suceder que ciertos circuitos el\u00e9ctricos an\u00f3malos tomen el control, haciendo que el coraz\u00f3n lata demasiado r\u00e1pido: eso se llama <strong>taquicardia.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9932c6c e-flex e-con-boxed e-con e-parent\" data-id=\"9932c6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8c8d9d6 e-con-full e-flex e-con e-child\" data-id=\"8c8d9d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48e616b elementor-widget elementor-widget-text-editor\" data-id=\"48e616b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estos trastornos del ritmo no siempre causan una ca\u00edda de la presi\u00f3n arterial, pero en algunas ocasiones pueden provocar una <strong>disminuci\u00f3n s\u00fabita de la presi\u00f3n<\/strong>, lo que lleva a una p\u00e9rdida de conciencia.<\/p><p>En casos m\u00e1s raros, el s\u00edncope puede ser causado por un <strong>problema estructural del coraz\u00f3n<\/strong>, como una v\u00e1lvula card\u00edaca que no funciona correctamente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9b8b01 e-con-full e-flex e-con e-child\" data-id=\"c9b8b01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d37213 elementor-widget elementor-widget-image\" data-id=\"1d37213\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"207\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/syncope.jpg\" class=\"attachment-large size-large wp-image-11833\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f55a44 e-flex e-con-boxed e-con e-parent\" data-id=\"4f55a44\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aeb5608 e-flex e-con-boxed e-con e-child\" data-id=\"aeb5608\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c41995 elementor-widget elementor-widget-heading\" data-id=\"4c41995\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00fasqueda de s\u00edntomas antes del s\u00edncope<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d342a elementor-widget elementor-widget-text-editor\" data-id=\"b0d342a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En algunas personas, las <strong>palpitaciones <\/strong>\u2014ya sean latidos r\u00e1pidos, irregulares o, a veces, muy lentos\u2014 pueden preceder a la p\u00e9rdida de conciencia. Otras pueden sentir <strong>dolor en el pecho<\/strong> justo antes del desmayo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c163857 e-flex e-con-boxed e-con e-parent\" data-id=\"c163857\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b403816 e-flex e-con-boxed e-con e-child\" data-id=\"b403816\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e95a1b3 elementor-widget elementor-widget-heading\" data-id=\"e95a1b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una poblaci\u00f3n de mayor edad o con enfermedad card\u00edaca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b787b8 elementor-widget elementor-widget-text-editor\" data-id=\"9b787b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El s\u00edncope de origen card\u00edaco afecta con mayor frecuencia a las <strong>personas mayores<\/strong>, as\u00ed como a aquellas que padecen una <strong>enfermedad card\u00edaca conocida<\/strong>, como una arritmia, una enfermedad valvular o una insuficiencia card\u00edaca.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e516357 e-flex e-con-boxed e-con e-parent\" data-id=\"e516357\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aae857f e-flex e-con-boxed e-con e-child\" data-id=\"aae857f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41bbf81 elementor-widget elementor-widget-heading\" data-id=\"41bbf81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La evaluaci\u00f3n m\u00e9dica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4d4de elementor-widget elementor-widget-text-editor\" data-id=\"1f4d4de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para comprender adecuadamente un episodio de s\u00edncope, el m\u00e9dico debe recopilar una <strong>descripci\u00f3n lo m\u00e1s precisa posible<\/strong> de la situaci\u00f3n, como si tuviera que <strong>reconstruir una escena<\/strong> en todos sus detalles.<\/p><p>Cada elemento cuenta: el momento del d\u00eda, el nivel de hidrataci\u00f3n o alimentaci\u00f3n, lo que la persona estaba haciendo justo antes del malestar, la posible presencia de s\u00edntomas precursores, as\u00ed como si hubo un testigo, lesiones sufridas, da\u00f1os materiales si los hubo, la forma en que regres\u00f3 la conciencia, la existencia o no de incontinencia urinaria, y el estado general al despertar.<\/p><p>Toda esta informaci\u00f3n, reunida, permite orientar el diagn\u00f3stico y definir mejor qu\u00e9 ex\u00e1menes deben realizarse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa7288d e-con-full e-flex e-con e-child\" data-id=\"aa7288d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a42721 elementor-widget elementor-widget-image\" data-id=\"8a42721\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/detective-212x300.png\" class=\"attachment-medium size-medium wp-image-4318\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/detective-212x300.png 212w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/detective-723x1024.png 723w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/detective-768x1087.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/02\/detective.png 904w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd08310 e-flex e-con-boxed e-con e-parent\" data-id=\"cd08310\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0c38fca e-flex e-con-boxed e-con e-child\" data-id=\"0c38fca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c941021 elementor-widget elementor-widget-heading\" data-id=\"c941021\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El examen del paciente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f3abbd elementor-widget elementor-widget-text-editor\" data-id=\"2f3abbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante la evaluaci\u00f3n cl\u00ednica, el m\u00e9dico prestar\u00e1 especial atenci\u00f3n a varios elementos clave.<\/p><ul><li><strong>Medir la presi\u00f3n arterial<\/strong>, primero acostado y luego de pie, es fundamental para detectar una ca\u00edda anormal de la presi\u00f3n.<\/li><li>La <strong>auscultaci\u00f3n del coraz\u00f3n<\/strong> permitir\u00e1 detectar posibles trastornos del ritmo (arritmias) o ruidos inusuales, ya sea a nivel de los <strong>vasos del cuello<\/strong> o de las v\u00e1lvulas card\u00edacas.<br \/><br \/><\/li><\/ul><p>Tambi\u00e9n se realiza <strong>un examen neurol\u00f3gico <\/strong>para evaluar la motricidad, la sensibilidad, el equilibrio y posibles signos relacionados con el sistema nervioso, con el fin de no pasar por alto una causa no card\u00edaca.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ed3aeb e-flex e-con-boxed e-con e-parent\" data-id=\"2ed3aeb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-87d356e e-flex e-con-boxed e-con e-child\" data-id=\"87d356e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8d3bea elementor-widget elementor-widget-heading\" data-id=\"f8d3bea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 ex\u00e1menes pueden solicitarse?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d698b15 elementor-widget elementor-widget-text-editor\" data-id=\"d698b15\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los ex\u00e1menes elegidos dependen ante todo de la impresi\u00f3n cl\u00ednica del m\u00e9dico, seg\u00fan la naturaleza del s\u00edncope y los antecedentes del paciente.<\/p><ul><li><strong>Electrocardiograma (ECG)<\/strong><\/li><\/ul><p>En general, el electrocardiograma (ECG) constituye el punto de partida de la evaluaci\u00f3n. Este examen consiste en colocar sensores el\u00e9ctricos sobre el t\u00f3rax para registrar la actividad el\u00e9ctrica del coraz\u00f3n. Permite detectar r\u00e1pidamente ciertas anomal\u00edas, como arritmias o signos de sufrimiento card\u00edaco.<\/p><p>La investigaci\u00f3n cl\u00ednica de un s\u00edncope de origen card\u00edaco puede agruparse en tres categor\u00edas:<br \/>\u2022 La b\u00fasqueda de un trastorno del ritmo<br \/>\u2022 La verificaci\u00f3n de las estructuras card\u00edacas<br \/>\u2022 La detecci\u00f3n de una enfermedad de las arterias coronarias.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb788d8 e-flex e-con-boxed e-con e-parent\" data-id=\"fb788d8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a452b4a e-flex e-con-boxed e-con e-child\" data-id=\"a452b4a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba7540 elementor-widget elementor-widget-heading\" data-id=\"5ba7540\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00fasqueda de un trastorno del ritmo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a0650e elementor-widget elementor-widget-text-editor\" data-id=\"8a0650e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Existen varias modalidades disponibles para investigar un trastorno del ritmo que pueda haber causado el desmayo.<\/p><ul><li><strong>Monitoreo card\u00edaco continuo<\/strong><\/li><\/ul><p>En contextos de urgencia o durante una hospitalizaci\u00f3n, se puede utilizar la telemetr\u00eda card\u00edaca. Se trata de una forma de vigilancia continua del ritmo card\u00edaco, visualizado en tiempo real en una pantalla. Esta tecnolog\u00eda es \u00fatil para detectar anomal\u00edas transitorias o seguir a pacientes con arritmias ya conocidas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a9efcb e-flex e-con-boxed e-con e-parent\" data-id=\"9a9efcb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f5f9600 e-flex e-con-boxed e-con e-child\" data-id=\"f5f9600\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1485e0b elementor-widget elementor-widget-text-editor\" data-id=\"1485e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Holter<\/strong><\/li><\/ul><p>Para las personas que presentan s\u00edntomas frecuentes, se puede proponer un monitor Holter, un peque\u00f1o dispositivo que se lleva durante 24 a 48 horas en casa o en el hospital. Registra de forma continua la actividad card\u00edaca con el fin de captar cualquier evento sospechoso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a97921 e-flex e-con-boxed e-con e-parent\" data-id=\"3a97921\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b86546f e-flex e-con-boxed e-con e-child\" data-id=\"b86546f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f32d79 elementor-widget elementor-widget-text-editor\" data-id=\"4f32d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Monitoreo externo prolongado<\/strong><\/li><\/ul><p>Cuando los episodios son poco frecuentes y ocurren a intervalos m\u00e1s largos, se puede utilizar un cardiomemo, tambi\u00e9n llamado telemonitor card\u00edaco. Este dispositivo externo se lleva durante un per\u00edodo prolongado, a menudo hasta dos semanas, y permite registrar la actividad card\u00edaca justo cuando se presentan los s\u00edntomas.<\/p><p>En un contexto m\u00e1s cotidiano, el uso de herramientas personales como un <strong>reloj inteligente<\/strong> o un dispositivo como <strong>Kardia<\/strong> tambi\u00e9n puede ser muy \u00fatil. Estas tecnolog\u00edas permiten que el paciente registre su ritmo card\u00edaco por s\u00ed mismo en el momento en que siente malestar, proporcionando as\u00ed datos valiosos al equipo m\u00e9dico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bf9557 e-con-full e-flex e-con e-child\" data-id=\"4bf9557\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-649572c elementor-widget elementor-widget-image\" data-id=\"649572c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"431\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/11\/montre-intel-768x431.jpg\" class=\"attachment-medium_large size-medium_large wp-image-9746\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/11\/montre-intel-768x431.jpg 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/11\/montre-intel-300x169.jpg 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/11\/montre-intel-1024x575.jpg 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/11\/montre-intel.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a45432f e-flex e-con-boxed e-con e-parent\" data-id=\"a45432f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-84bac15 e-flex e-con-boxed e-con e-child\" data-id=\"84bac15\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-578db2e elementor-widget elementor-widget-text-editor\" data-id=\"578db2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Monitoreo subcut\u00e1neo temporal<\/strong><\/li><\/ul><p>Cuando la sospecha de un trastorno del ritmo card\u00edaco persiste a pesar de ex\u00e1menes iniciales normales, se puede recomendar un monitor implantable. Este peque\u00f1o dispositivo se inserta bajo la piel, a nivel del t\u00f3rax, mediante un procedimiento menor.<\/p><p>Su principal ventaja es que permite una vigilancia continua y prolongada de la actividad el\u00e9ctrica del coraz\u00f3n, a veces durante varios meses. Aumenta as\u00ed las probabilidades de detectar un evento raro o transitorio, especialmente cuando los episodios son poco frecuentes pero preocupantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-630e750 e-flex e-con-boxed e-con e-parent\" data-id=\"630e750\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8def967 e-flex e-con-boxed e-con e-child\" data-id=\"8def967\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32b331b elementor-widget elementor-widget-text-editor\" data-id=\"32b331b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Para los pacientes con marcapasos permanente<\/strong><\/p><p>En las personas portadoras de un marcapasos permanente, la b\u00fasqueda de una posible arritmia se ve considerablemente facilitada. Este dispositivo, adem\u00e1s de estimular el coraz\u00f3n cuando es necesario, registra de forma continua la actividad el\u00e9ctrica card\u00edaca.<\/p><p>Cuando ocurre un episodio de s\u00edncope, el m\u00e9dico puede interrogar el marcapasos para recuperar con precisi\u00f3n los datos registrados en el momento del malestar. Este an\u00e1lisis espec\u00edfico permite a menudo identificar la causa del episodio, ya sea un trastorno del ritmo u otra anomal\u00eda. Se trata de una herramienta diagn\u00f3stica valiosa, confiable y de acceso r\u00e1pido en consulta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5274a0c e-flex e-con-boxed e-con e-parent\" data-id=\"5274a0c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-412600d e-flex e-con-boxed e-con e-child\" data-id=\"412600d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38bee85 elementor-widget elementor-widget-heading\" data-id=\"38bee85\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Evaluaci\u00f3n de la estructura card\u00edaca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e45c833 elementor-widget elementor-widget-text-editor\" data-id=\"e45c833\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por otro lado, si se sospecha una alteraci\u00f3n estructural del coraz\u00f3n, generalmente se solicita una <strong>ecocardiograf\u00eda transtor\u00e1cica<\/strong>. Esta prueba de imagen, similar a una ecograf\u00eda obst\u00e9trica, permite evaluar el funcionamiento del m\u00fasculo card\u00edaco y el estado de las v\u00e1lvulas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92a34f4 e-flex e-con-boxed e-con e-parent\" data-id=\"92a34f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8992d03 e-flex e-con-boxed e-con e-child\" data-id=\"8992d03\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2693fb elementor-widget elementor-widget-heading\" data-id=\"c2693fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00fasqueda de una enfermedad de las arterias del coraz\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c56a49 e-flex e-con-boxed e-con e-parent\" data-id=\"0c56a49\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e568a72 e-flex e-con-boxed e-con e-child\" data-id=\"e568a72\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d978e71 elementor-widget elementor-widget-text-editor\" data-id=\"d978e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Finalmente, cuando se sospecha un problema en las arterias coronarias, se pueden prescribir otros ex\u00e1menes para completar la evaluaci\u00f3n. Uno de ellos puede ser una <strong>prueba de esfuerzo en cinta rodante<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82e8ddd e-flex e-con-boxed e-con e-child\" data-id=\"82e8ddd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93d8619 elementor-widget elementor-widget-image\" data-id=\"93d8619\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"258\" height=\"300\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/03\/Tapis_roulant-258x300.jpg\" class=\"attachment-medium size-medium wp-image-4942\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/03\/Tapis_roulant-258x300.jpg 258w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/03\/Tapis_roulant-880x1024.jpg 880w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/03\/Tapis_roulant-768x894.jpg 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/03\/Tapis_roulant-1320x1536.jpg 1320w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/03\/Tapis_roulant-1760x2048.jpg 1760w\" sizes=\"(max-width: 258px) 100vw, 258px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9499706 e-flex e-con-boxed e-con e-parent\" data-id=\"9499706\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5e5f4ff e-flex e-con-boxed e-con e-child\" data-id=\"5e5f4ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4492e51 elementor-widget elementor-widget-text-editor\" data-id=\"4492e51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tambi\u00e9n existen otros m\u00e9todos posibles, como los ex\u00e1menes de <strong>medicina nuclear<\/strong>, que permiten observar la circulaci\u00f3n sangu\u00ednea en el coraz\u00f3n.<\/p><p>En ciertos casos, puede indicarse una <strong>coronariograf\u00eda<\/strong> para visualizar directamente las arterias coronarias mediante el uso de un medio de contraste.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-495a61f e-flex e-con-boxed e-con e-parent\" data-id=\"495a61f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ab4504e e-flex e-con-boxed e-con e-child\" data-id=\"ab4504e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04f5f3c elementor-widget elementor-widget-heading\" data-id=\"04f5f3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son los riesgos para la salud?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3cb0d3 e-flex e-con-boxed e-con e-parent\" data-id=\"d3cb0d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a1f5193 e-flex e-con-boxed e-con e-child\" data-id=\"a1f5193\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-125cc04 elementor-widget elementor-widget-text-editor\" data-id=\"125cc04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entre los distintos tipos de s\u00edncope, el de origen card\u00edaco (s\u00edncope cardiog\u00e9nico) es el que presenta los mayores riesgos. A diferencia de los s\u00edncopes reflejos, no responde a las maniobras preventivas habituales y suele ocurrir de forma repentina, sin se\u00f1ales de advertencia.<\/p><p>Este car\u00e1cter imprevisible <strong>aumenta considerablemente el riesgo de lesiones<\/strong>, especialmente si la ca\u00edda ocurre sobre una superficie dura o en un entorno peligroso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f539a69 e-con-full e-flex e-con e-child\" data-id=\"f539a69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5529ea elementor-widget elementor-widget-image\" data-id=\"b5529ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"241\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/chute-300x241.png\" class=\"attachment-medium size-medium wp-image-11869\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/chute-300x241.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/chute-1024x824.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/chute-768x618.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2025\/03\/chute.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f42efaa e-flex e-con-boxed e-con e-parent\" data-id=\"f42efaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-869e1ec e-flex e-con-boxed e-con e-child\" data-id=\"869e1ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afad39b elementor-widget elementor-widget-text-editor\" data-id=\"afad39b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En casos poco frecuentes, este tipo de s\u00edncope puede ser indicativo de una <strong>enfermedad card\u00edaca grave <\/strong>e incluso causar una <strong>muerte s\u00fabita<\/strong>, especialmente si est\u00e1 relacionado con una arritmia maligna o una patolog\u00eda card\u00edaca subyacente no tratada. Por lo tanto, es fundamental realizar una <strong>evaluaci\u00f3n m\u00e9dica r\u00e1pida<\/strong> y detallada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a1e28f e-flex e-con-boxed e-con e-parent\" data-id=\"6a1e28f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-94702a4 e-flex e-con-boxed e-con e-child\" data-id=\"94702a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbd11 elementor-widget elementor-widget-heading\" data-id=\"77fbd11\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1l es el tratamiento?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9447cee elementor-widget elementor-widget-text-editor\" data-id=\"9447cee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como se mencion\u00f3 anteriormente, el s\u00edncope de origen card\u00edaco puede tener causas variadas, y su tratamiento depende directamente de los resultados de la evaluaci\u00f3n m\u00e9dica.<\/p><p>El objetivo es <strong>tratar la causa subyacente<\/strong>, ya sea un trastorno del ritmo card\u00edaco (problema el\u00e9ctrico), una enfermedad valvular (afectaci\u00f3n de las v\u00e1lvulas del coraz\u00f3n) o una disfunci\u00f3n de las arterias coronarias.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51f36f1 e-flex e-con-boxed e-con e-parent\" data-id=\"51f36f1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7dec7fd e-flex e-con-boxed e-con e-child\" data-id=\"7dec7fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9114cd7 elementor-widget elementor-widget-heading\" data-id=\"9114cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mensaje clave<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dc44ee elementor-widget elementor-widget-text-editor\" data-id=\"9dc44ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El s\u00edncope card\u00edaco es una p\u00e9rdida repentina del conocimiento causada por <strong>un problema en el coraz\u00f3n<\/strong>. A diferencia de otros tipos de malestar que aparecen de manera gradual o que ofrecen se\u00f1ales de advertencia, este tipo ocurre <strong>sin previo<\/strong> aviso. Esto lo hace especialmente peligroso.<\/p><p>El mayor riesgo del s\u00edncope card\u00edaco es la <strong>ca\u00edda brusca<\/strong> que lo acompa\u00f1a. Como la persona no tiene tiempo de sentarse o apoyarse, puede caer con todo su peso, a veces sobre superficies duras o contra objetos.<\/p><p>Por eso, es <strong>urgente consultar a un m\u00e9dico<\/strong> sin demora si hay una herida en la cabeza, por m\u00ednima que sea, o si se sospecha una fractura \u00f3sea asociada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8273bae e-con-full e-flex e-con e-child\" data-id=\"8273bae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-545e7cc elementor-widget elementor-widget-image\" data-id=\"545e7cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/04\/la-cle-1024x682.jpg\" class=\"attachment-large size-large wp-image-5225\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/04\/la-cle-1024x682.jpg 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/04\/la-cle-300x200.jpg 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/04\/la-cle-768x512.jpg 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/04\/la-cle.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c59d2a6\" data-id=\"c59d2a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ec5735 elementor-search-form--skin-classic elementor-search-form--button-type-icon elementor-search-form--icon-search elementor-widget elementor-widget-global elementor-global-4750 elementor-global-3416 elementor-widget-search-form\" data-id=\"5ec5735\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;classic&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"search-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<search role=\"search\">\n\t\t\t<form class=\"elementor-search-form\" action=\"https:\/\/icardio.ca\/es\/\" method=\"get\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-search-form__container\">\n\t\t\t\t\t<label class=\"elementor-screen-only\" for=\"elementor-search-form-5ec5735\">Buscar<\/label>\n\n\t\t\t\t\t\n\t\t\t\t\t<input id=\"elementor-search-form-5ec5735\" placeholder=\"Buscar...\" class=\"elementor-search-form__input\" type=\"search\" name=\"s\" value=\"\">\n\t\t\t\t\t<input type='hidden' name='lang' value='es' \/>\n\t\t\t\t\t\t\t\t\t\t\t<button class=\"elementor-search-form__submit\" type=\"submit\" aria-label=\"Buscar\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-font-icon-svg-container\"><svg class=\"fa fa-search e-font-icon-svg e-fas-search\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M505 442.7L405.3 343c-4.5-4.5-10.6-7-17-7H372c27.6-35.3 44-79.7 44-128C416 93.1 322.9 0 208 0S0 93.1 0 208s93.1 208 208 208c48.3 0 92.7-16.4 128-44v16.3c0 6.4 2.5 12.5 7 17l99.7 99.7c9.4 9.4 24.6 9.4 33.9 0l28.3-28.3c9.4-9.4 9.4-24.6.1-34zM208 336c-70.7 0-128-57.2-128-128 0-70.7 57.2-128 128-128 70.7 0 128 57.2 128 128 0 70.7-57.2 128-128 128z\"><\/path><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t<\/search>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-515dff8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"515dff8d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-72235494\" data-id=\"72235494\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81fce3d elementor-widget elementor-widget-global elementor-global-4738 elementor-global-3406 elementor-widget-heading\" data-id=\"81fce3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Comparte este art\u00edculo<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12eded0 e-flex e-con-boxed e-con e-parent\" data-id=\"12eded0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-199f7ba uael-share-buttons--view-text elementor-share-buttons--align-center uael-stylex-inline elementor-grid-0 elementor-widget elementor-widget-global elementor-global-4732 elementor-global-3396 elementor-widget-uael-social-share\" data-id=\"199f7ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;alignment&quot;:&quot;center&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;button_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.75,&quot;sizes&quot;:[]},&quot;button_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;0&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;row_gap_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_size_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_size_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;border_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;border_size_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;border_size_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;border_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;border_size_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;border_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-style-inline uael-container uael-floating-align-\" data-pin_data_url=\"\" data-share_url_type=\"current_page\" data-share_url=\"\">\n\t\t\t<div class=\"elementor-grid uael-floating-align-\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-facebook\">\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation-pulse uaelbtn-shape-circle uaelbtn--skin-boxed\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-twitter\">\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation-pulse uaelbtn-shape-circle uaelbtn--skin-boxed\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-linkedin\">\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation-pulse uaelbtn-shape-circle uaelbtn--skin-boxed\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\t\t\tLinkedin\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-whatsapp\">\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation-pulse uaelbtn-shape-circle uaelbtn--skin-boxed\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\t\t\tWhatsapp\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-email\">\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation-pulse uaelbtn-shape-circle uaelbtn--skin-boxed\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-print\">\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation-pulse uaelbtn-shape-circle uaelbtn--skin-boxed\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\t\t\tImprimir\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a28e6b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a28e6b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-44961b4\" data-id=\"44961b4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4c1be8 elementor-widget elementor-widget-global elementor-global-4746 elementor-global-3413 elementor-widget-heading\" data-id=\"a4c1be8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Art\u00edculos relacionados<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8720d47 elementor-grid-1 elementor-posts--thumbnail-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-global elementor-global-4754 elementor-global-3422 elementor-widget-posts\" data-id=\"8720d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-9128 post type-post status-publish format-standard has-post-thumbnail hentry category-general-es category-general category-prevencion category-prevention tag-article-mis-de-lavant\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/regreso-al-deporte\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-hockey-300x168.png\" class=\"attachment-medium size-medium wp-image-9129\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-hockey-300x168.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-hockey-1024x574.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-hockey-768x430.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-hockey.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/regreso-al-deporte\/\" >\n\t\t\t\tRegreso al Deporte\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 de septiembre de 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/regreso-al-deporte\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Regreso al Deporte\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-7757 post type-post status-publish format-standard has-post-thumbnail hentry category-general-es category-prevencion category-prevention tag-article-mis-de-lavant\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/un-corazon-sano-mediante-habitos-alimentacion-equilibrada-y-consumo-de-alcohol\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"208\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/06\/coeur-habitude-300x208.jpg\" class=\"attachment-medium size-medium wp-image-7758\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/06\/coeur-habitude-300x208.jpg 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/06\/coeur-habitude-1024x710.jpg 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/06\/coeur-habitude-768x533.jpg 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/06\/coeur-habitude.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/un-corazon-sano-mediante-habitos-alimentacion-equilibrada-y-consumo-de-alcohol\/\" >\n\t\t\t\tUn coraz\u00f3n sano mediante h\u00e1bitos: &#8211; Alimentaci\u00f3n equilibrada y consumo de alcohol\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12 de junio de 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/un-corazon-sano-mediante-habitos-alimentacion-equilibrada-y-consumo-de-alcohol\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Un coraz\u00f3n sano mediante h\u00e1bitos: &#8211; Alimentaci\u00f3n equilibrada y consumo de alcohol\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8870 post type-post status-publish format-standard has-post-thumbnail hentry category-general-es category-prevencion tag-article-mis-de-lavant\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/habitos-de-vida-saludables-la-calidad-y-la-duracion-del-sueno\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-nuit-300x169.png\" class=\"attachment-medium size-medium wp-image-8871\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-nuit-300x169.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-nuit-1024x576.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-nuit-768x432.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2024\/09\/coeur-nuit.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/habitos-de-vida-saludables-la-calidad-y-la-duracion-del-sueno\/\" >\n\t\t\t\tH\u00e1bitos de vida saludables &#8211; La calidad y la duraci\u00f3n del sue\u00f1o.\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 de septiembre de 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/habitos-de-vida-saludables-la-calidad-y-la-duracion-del-sueno\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre H\u00e1bitos de vida saludables &#8211; La calidad y la duraci\u00f3n del sue\u00f1o.\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-246972f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"246972f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-94a8515\" data-id=\"94a8515\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43a10fe elementor-widget elementor-widget-global elementor-global-4742 elementor-global-3410 elementor-widget-heading\" data-id=\"43a10fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00faltimos art\u00edculos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0844166 elementor-grid-1 elementor-posts--thumbnail-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-global elementor-global-4752 elementor-global-3419 elementor-widget-posts\" data-id=\"0844166\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-18469 post type-post status-publish format-standard has-post-thumbnail hentry category-actualite category-prevention tag-articles-mis-de-lavant\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/el-corazon-no-se-toma-vacaciones\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/07\/coeur-plage-cocktail-300x200.png\" class=\"attachment-medium size-medium wp-image-18470\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/07\/coeur-plage-cocktail-300x200.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/07\/coeur-plage-cocktail-1024x683.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/07\/coeur-plage-cocktail-768x512.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/07\/coeur-plage-cocktail.png 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/el-corazon-no-se-toma-vacaciones\/\" >\n\t\t\t\tEl coraz\u00f3n no se toma vacaciones\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t20 de julio de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/el-corazon-no-se-toma-vacaciones\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre El coraz\u00f3n no se toma vacaciones\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-18375 post type-post status-publish format-standard has-post-thumbnail hentry category-enfermedades-coronarias category-enfermedades-valvulares-y-cardiovasculares tag-articles-mis-de-lavant-es-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/oclusion-total-cronica-cto-de-una-arteria-coronaria-explicacion-medica\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-route-300x300.png\" class=\"attachment-medium size-medium wp-image-18376\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-route-300x300.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-route-1024x1024.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-route-150x150.png 150w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-route-768x768.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-route.png 1254w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/oclusion-total-cronica-cto-de-una-arteria-coronaria-explicacion-medica\/\" >\n\t\t\t\tOclusi\u00f3n total cr\u00f3nica (CTO) de una arteria coronaria: explicaci\u00f3n m\u00e9dica\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t29 de junio de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/oclusion-total-cronica-cto-de-una-arteria-coronaria-explicacion-medica\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Oclusi\u00f3n total cr\u00f3nica (CTO) de una arteria coronaria: explicaci\u00f3n m\u00e9dica\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-18234 post type-post status-publish format-standard has-post-thumbnail hentry category-enfermedades-valvulares-y-cardiovasculares tag-articles-mis-de-lavant-es-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/pericarditis-aguda-generalidades\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-feu-300x200.png\" class=\"attachment-medium size-medium wp-image-18235\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-feu-300x200.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-feu-1024x683.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-feu-768x512.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-feu.png 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/pericarditis-aguda-generalidades\/\" >\n\t\t\t\tPericarditis aguda &#8211; Generalidades\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t14 de junio de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/pericarditis-aguda-generalidades\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Pericarditis aguda &#8211; Generalidades\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-18195 post type-post status-publish format-standard has-post-thumbnail hentry category-alimentacion tag-articles-mis-de-lavant-es-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/ravioli-de-chirivia-con-salvia-carpaccio-de-remolacha-y-nabo-a-la-naranja\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Raviole-de-panais-a-la-sauge-300x206.jpg\" class=\"attachment-medium size-medium wp-image-18196\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Raviole-de-panais-a-la-sauge-300x206.jpg 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Raviole-de-panais-a-la-sauge.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/ravioli-de-chirivia-con-salvia-carpaccio-de-remolacha-y-nabo-a-la-naranja\/\" >\n\t\t\t\tRavioli de chiriv\u00eda con salvia, carpaccio de remolacha y nabo a la naranja\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13 de junio de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/ravioli-de-chirivia-con-salvia-carpaccio-de-remolacha-y-nabo-a-la-naranja\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Ravioli de chiriv\u00eda con salvia, carpaccio de remolacha y nabo a la naranja\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-18147 post type-post status-publish format-standard has-post-thumbnail hentry category-busqueda-clinica tag-articles-mis-de-lavant-es-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/la-investigacion-clinica-impulsando-el-progreso-de-la-medicina\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-Recherche-300x200.png\" class=\"attachment-medium size-medium wp-image-18148\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-Recherche-300x200.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-Recherche-1024x684.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-Recherche-768x513.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/Coeur-Recherche.png 1535w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/la-investigacion-clinica-impulsando-el-progreso-de-la-medicina\/\" >\n\t\t\t\tLa investigaci\u00f3n cl\u00ednica: impulsando el progreso de la medicina\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12 de junio de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/la-investigacion-clinica-impulsando-el-progreso-de-la-medicina\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre La investigaci\u00f3n cl\u00ednica: impulsando el progreso de la medicina\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-18096 post type-post status-publish format-standard has-post-thumbnail hentry category-examenes tag-articles-mis-de-lavant-es-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/icardio.ca\/es\/monitorizacion-cardiaca-externa-prolongada\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"202\" src=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-tatou-300x202.png\" class=\"attachment-medium size-medium wp-image-18097\" alt=\"\" srcset=\"https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-tatou-300x202.png 300w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-tatou-1024x689.png 1024w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-tatou-768x516.png 768w, https:\/\/icardio.ca\/wp-content\/uploads\/2026\/06\/coeur-tatou.png 1029w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h5 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/icardio.ca\/es\/monitorizacion-cardiaca-externa-prolongada\/\" >\n\t\t\t\tMonitorizaci\u00f3n card\u00edaca externa prolongada\t\t\t<\/a>\n\t\t<\/h5>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 de junio de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/icardio.ca\/es\/monitorizacion-cardiaca-externa-prolongada\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Monitorizaci\u00f3n card\u00edaca externa prolongada\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Como su nombre lo indica, el s\u00edncope card\u00edaco es causado por un problema en el coraz\u00f3n. Es una de las formas de s\u00edncope que requiere especial atenci\u00f3n, ya que puede ser se\u00f1al de un trastorno card\u00edaco m\u00e1s serio.<br \/>\nEn la gran mayor\u00eda de los casos, est\u00e1 relacionado con un trastorno del ritmo card\u00edaco. <\/p>\n","protected":false},"author":4,"featured_media":12113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[42],"class_list":["post-12112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-articles-mis-de-lavant"],"_links":{"self":[{"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/posts\/12112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/comments?post=12112"}],"version-history":[{"count":5,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/posts\/12112\/revisions"}],"predecessor-version":[{"id":12119,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/posts\/12112\/revisions\/12119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/media\/12113"}],"wp:attachment":[{"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/media?parent=12112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/categories?post=12112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icardio.ca\/es\/wp-json\/wp\/v2\/tags?post=12112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}